{"id":6295,"date":"2025-03-09T18:40:19","date_gmt":"2025-03-09T18:40:19","guid":{"rendered":"https:\/\/www.perfumeparlour.es\/?post_type=product&#038;p=6295"},"modified":"2026-05-10T15:20:14","modified_gmt":"2026-05-10T15:20:14","slug":"pennine-for-men-1008-pertenece-a-la-familia-de-notas-olfativas-similares-a-carlisle-parfums-de-marly","status":"publish","type":"product","link":"https:\/\/www.perfumeparlour.es\/en\/product\/pennine-for-men-1008-pertenece-a-la-familia-de-notas-olfativas-similares-a-carlisle-parfums-de-marly\/","title":{"rendered":"PENNINE FOR MEN &#8211; 1008 &#8211; Pertenece a la familia de notas olfativas similares a Carlisle &#8211; Parfums de Marly\u00ae"},"content":{"rendered":"<h4>Nota alta:<\/h4>\n<h4>Manzana verde\u00a0 \u00a0<a href=\"https:\/\/www.perfumeparlour.es\/wp-content\/uploads\/2025\/03\/MANZANA-VERDE.jpg\"><img decoding=\"async\" class=\"alignnone size-medium wp-image-6306\" src=\"https:\/\/www.perfumeparlour.es\/wp-content\/uploads\/2025\/03\/MANZANA-VERDE.jpg\" alt=\"\" width=\"120\" height=\"120\" srcset=\"https:\/\/www.perfumeparlour.es\/wp-content\/uploads\/2025\/03\/MANZANA-VERDE.jpg 120w, https:\/\/www.perfumeparlour.es\/wp-content\/uploads\/2025\/03\/MANZANA-VERDE-12x12.jpg 12w, https:\/\/www.perfumeparlour.es\/wp-content\/uploads\/2025\/03\/MANZANA-VERDE-55x55.jpg 55w, https:\/\/www.perfumeparlour.es\/wp-content\/uploads\/2025\/03\/MANZANA-VERDE-100x100.jpg 100w\" sizes=\"(max-width: 120px) 100vw, 120px\" \/><\/a>\u00a0 Nuez moscada\u00a0 <a href=\"https:\/\/www.perfumeparlour.es\/wp-content\/uploads\/2025\/02\/NUEZ-MOSCADA.jpg\"><img decoding=\"async\" class=\"alignnone size-full wp-image-5961\" src=\"https:\/\/www.perfumeparlour.es\/wp-content\/uploads\/2025\/02\/NUEZ-MOSCADA.jpg\" alt=\"\" width=\"120\" height=\"120\" srcset=\"https:\/\/www.perfumeparlour.es\/wp-content\/uploads\/2025\/02\/NUEZ-MOSCADA.jpg 120w, https:\/\/www.perfumeparlour.es\/wp-content\/uploads\/2025\/02\/NUEZ-MOSCADA-12x12.jpg 12w, https:\/\/www.perfumeparlour.es\/wp-content\/uploads\/2025\/02\/NUEZ-MOSCADA-55x55.jpg 55w, https:\/\/www.perfumeparlour.es\/wp-content\/uploads\/2025\/02\/NUEZ-MOSCADA-100x100.jpg 100w\" sizes=\"(max-width: 120px) 100vw, 120px\" \/><\/a>\u00a0 \u00a0Azafgran\u00a0 <a href=\"https:\/\/www.perfumeparlour.es\/wp-content\/uploads\/2025\/02\/AZAFRAN.jpg\"><img decoding=\"async\" class=\"alignnone size-full wp-image-5954\" src=\"https:\/\/www.perfumeparlour.es\/wp-content\/uploads\/2025\/02\/AZAFRAN.jpg\" alt=\"\" width=\"120\" height=\"120\" srcset=\"https:\/\/www.perfumeparlour.es\/wp-content\/uploads\/2025\/02\/AZAFRAN.jpg 120w, https:\/\/www.perfumeparlour.es\/wp-content\/uploads\/2025\/02\/AZAFRAN-12x12.jpg 12w, https:\/\/www.perfumeparlour.es\/wp-content\/uploads\/2025\/02\/AZAFRAN-55x55.jpg 55w, https:\/\/www.perfumeparlour.es\/wp-content\/uploads\/2025\/02\/AZAFRAN-100x100.jpg 100w\" sizes=\"(max-width: 120px) 100vw, 120px\" \/><\/a><\/h4>\n<hr \/>\n<p><strong>Nota media: <\/strong><\/p>\n<p><strong>\u00a0Rosa\u00a0 \u00a0 <a href=\"https:\/\/www.perfumeparlour.es\/wp-content\/uploads\/2025\/02\/ROSA.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-5965\" src=\"https:\/\/www.perfumeparlour.es\/wp-content\/uploads\/2025\/02\/ROSA.jpg\" alt=\"\" width=\"120\" height=\"120\" srcset=\"https:\/\/www.perfumeparlour.es\/wp-content\/uploads\/2025\/02\/ROSA.jpg 120w, https:\/\/www.perfumeparlour.es\/wp-content\/uploads\/2025\/02\/ROSA-12x12.jpg 12w, https:\/\/www.perfumeparlour.es\/wp-content\/uploads\/2025\/02\/ROSA-55x55.jpg 55w, https:\/\/www.perfumeparlour.es\/wp-content\/uploads\/2025\/02\/ROSA-100x100.jpg 100w\" sizes=\"(max-width: 120px) 100vw, 120px\" \/><\/a><\/strong><\/p>\n<hr \/>\n<p><strong>Nota base:<\/strong><\/p>\n<p><strong>Hoha de tabaco\u00a0 <a href=\"https:\/\/www.perfumeparlour.es\/wp-content\/uploads\/2025\/02\/TABACO.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-6019\" src=\"https:\/\/www.perfumeparlour.es\/wp-content\/uploads\/2025\/02\/TABACO.jpg\" alt=\"\" width=\"160\" height=\"106\" srcset=\"https:\/\/www.perfumeparlour.es\/wp-content\/uploads\/2025\/02\/TABACO.jpg 271w, https:\/\/www.perfumeparlour.es\/wp-content\/uploads\/2025\/02\/TABACO-18x12.jpg 18w\" sizes=\"(max-width: 160px) 100vw, 160px\" \/><\/a> \u00a0 \u00a0haba tonka\u00a0 <a href=\"https:\/\/www.perfumeparlour.es\/wp-content\/uploads\/2025\/02\/HABA-TONKA.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-5958\" src=\"https:\/\/www.perfumeparlour.es\/wp-content\/uploads\/2025\/02\/HABA-TONKA.jpg\" alt=\"\" width=\"120\" height=\"120\" srcset=\"https:\/\/www.perfumeparlour.es\/wp-content\/uploads\/2025\/02\/HABA-TONKA.jpg 120w, https:\/\/www.perfumeparlour.es\/wp-content\/uploads\/2025\/02\/HABA-TONKA-12x12.jpg 12w, https:\/\/www.perfumeparlour.es\/wp-content\/uploads\/2025\/02\/HABA-TONKA-55x55.jpg 55w, https:\/\/www.perfumeparlour.es\/wp-content\/uploads\/2025\/02\/HABA-TONKA-100x100.jpg 100w\" sizes=\"(max-width: 120px) 100vw, 120px\" \/><\/a>\u00a0 \u00a0 Pachouli\u00a0 <a href=\"https:\/\/www.perfumeparlour.es\/wp-content\/uploads\/2025\/02\/PACHULI.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-5963\" src=\"https:\/\/www.perfumeparlour.es\/wp-content\/uploads\/2025\/02\/PACHULI.jpg\" alt=\"\" width=\"120\" height=\"120\" srcset=\"https:\/\/www.perfumeparlour.es\/wp-content\/uploads\/2025\/02\/PACHULI.jpg 120w, https:\/\/www.perfumeparlour.es\/wp-content\/uploads\/2025\/02\/PACHULI-12x12.jpg 12w, https:\/\/www.perfumeparlour.es\/wp-content\/uploads\/2025\/02\/PACHULI-55x55.jpg 55w, https:\/\/www.perfumeparlour.es\/wp-content\/uploads\/2025\/02\/PACHULI-100x100.jpg 100w\" sizes=\"(max-width: 120px) 100vw, 120px\" \/><\/a><\/strong><\/p>\n<div class=\"easytabs-content-item easytabs-content-item-static\" data-et-marker=\"tabs-triumphing-for-men-0929-s0\" data-et-handle=\"tabs-disclaimer\">\n<div class=\"easytabs-accordion-item\" tabindex=\"-1\" role=\"tab\" aria-labelledby=\"easytabs-slide-label-035-2\" aria-selected=\"false\"><\/div>\n<\/div>\n<p>&nbsp;<\/p>\n<h4>Esta es una fragancia floral afrutada para hombres y mujeres.<\/h4>","protected":false},"excerpt":{"rendered":"<h6><em>Pertenece a la familia de notas olfativas similares a Carlisle &#8211; Parfums de Marly\u00ae<\/em><\/h6>\n<p>&nbsp;<\/p>","protected":false},"featured_media":7726,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[261,156,168,44,128,142,150,172,115,232],"product_tag":[],"class_list":{"0":"post-6295","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-amaderado","7":"product_cat-aromatico","8":"product_cat-floral","9":"product_cat-fragancias-para-hombres","10":"product_cat-fragancia-unisex","11":"product_cat-invierno","12":"product_cat-notas","13":"product_cat-oriental","14":"product_cat-otono","15":"product_cat-vainilla","17":"first","18":"instock","19":"shipping-taxable","20":"purchasable","21":"product-type-variable","22":"add-to-wishlist-after_add_to_cart"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>PENNINE FOR MEN - 1008 - Pertenece a la familia de notas olfativas similares a Carlisle - Parfums de Marly\u00ae - Perfumes Parlour<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.perfumeparlour.es\/en\/product\/pennine-for-men-1008-pertenece-a-la-familia-de-notas-olfativas-similares-a-carlisle-parfums-de-marly\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"PENNINE FOR MEN - 1008 - Pertenece a la familia de notas olfativas similares a Carlisle - Parfums de Marly\u00ae - Perfumes Parlour\" \/>\n<meta property=\"og:description\" content=\"Pertenece a la familia de notas olfativas similares a Carlisle - Parfums de Marly\u00ae &nbsp;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.perfumeparlour.es\/en\/product\/pennine-for-men-1008-pertenece-a-la-familia-de-notas-olfativas-similares-a-carlisle-parfums-de-marly\/\" \/>\n<meta property=\"og:site_name\" content=\"Perfumes Parlour\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-10T15:20:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.perfumeparlour.es\/wp-content\/uploads\/2025\/03\/Pennine-For-Men_45755bd3-4f46-4617-80ad-691fb281dbbd.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.perfumeparlour.es\\\/product\\\/pennine-for-men-1008-pertenece-a-la-familia-de-notas-olfativas-similares-a-carlisle-parfums-de-marly\\\/\",\"url\":\"https:\\\/\\\/www.perfumeparlour.es\\\/product\\\/pennine-for-men-1008-pertenece-a-la-familia-de-notas-olfativas-similares-a-carlisle-parfums-de-marly\\\/\",\"name\":\"PENNINE FOR MEN - 1008 - Pertenece a la familia de notas olfativas similares a Carlisle - Parfums de Marly\u00ae - Perfumes Parlour\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.perfumeparlour.es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.perfumeparlour.es\\\/product\\\/pennine-for-men-1008-pertenece-a-la-familia-de-notas-olfativas-similares-a-carlisle-parfums-de-marly\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.perfumeparlour.es\\\/product\\\/pennine-for-men-1008-pertenece-a-la-familia-de-notas-olfativas-similares-a-carlisle-parfums-de-marly\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.perfumeparlour.es\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/Pennine-For-Men_45755bd3-4f46-4617-80ad-691fb281dbbd.webp\",\"datePublished\":\"2025-03-09T18:40:19+00:00\",\"dateModified\":\"2026-05-10T15:20:14+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.perfumeparlour.es\\\/product\\\/pennine-for-men-1008-pertenece-a-la-familia-de-notas-olfativas-similares-a-carlisle-parfums-de-marly\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.perfumeparlour.es\\\/product\\\/pennine-for-men-1008-pertenece-a-la-familia-de-notas-olfativas-similares-a-carlisle-parfums-de-marly\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/www.perfumeparlour.es\\\/product\\\/pennine-for-men-1008-pertenece-a-la-familia-de-notas-olfativas-similares-a-carlisle-parfums-de-marly\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.perfumeparlour.es\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/Pennine-For-Men_45755bd3-4f46-4617-80ad-691fb281dbbd.webp\",\"contentUrl\":\"https:\\\/\\\/www.perfumeparlour.es\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/Pennine-For-Men_45755bd3-4f46-4617-80ad-691fb281dbbd.webp\",\"width\":800,\"height\":1200},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.perfumeparlour.es\\\/product\\\/pennine-for-men-1008-pertenece-a-la-familia-de-notas-olfativas-similares-a-carlisle-parfums-de-marly\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.perfumeparlour.es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tienda\",\"item\":\"https:\\\/\\\/www.perfumeparlour.es\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"PENNINE FOR MEN &#8211; 1008 &#8211; Pertenece a la familia de notas olfativas similares a Carlisle &#8211; Parfums de Marly\u00ae\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.perfumeparlour.es\\\/#website\",\"url\":\"https:\\\/\\\/www.perfumeparlour.es\\\/\",\"name\":\"Perfumes Parlour\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.perfumeparlour.es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"PENNINE FOR MEN - 1008 - Pertenece a la familia de notas olfativas similares a Carlisle - Parfums de Marly\u00ae - Perfumes Parlour","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.perfumeparlour.es\/en\/product\/pennine-for-men-1008-pertenece-a-la-familia-de-notas-olfativas-similares-a-carlisle-parfums-de-marly\/","og_locale":"en_GB","og_type":"article","og_title":"PENNINE FOR MEN - 1008 - Pertenece a la familia de notas olfativas similares a Carlisle - Parfums de Marly\u00ae - Perfumes Parlour","og_description":"Pertenece a la familia de notas olfativas similares a Carlisle - Parfums de Marly\u00ae &nbsp;","og_url":"https:\/\/www.perfumeparlour.es\/en\/product\/pennine-for-men-1008-pertenece-a-la-familia-de-notas-olfativas-similares-a-carlisle-parfums-de-marly\/","og_site_name":"Perfumes Parlour","article_modified_time":"2026-05-10T15:20:14+00:00","og_image":[{"width":800,"height":1200,"url":"https:\/\/www.perfumeparlour.es\/wp-content\/uploads\/2025\/03\/Pennine-For-Men_45755bd3-4f46-4617-80ad-691fb281dbbd.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_misc":{"Estimated reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.perfumeparlour.es\/product\/pennine-for-men-1008-pertenece-a-la-familia-de-notas-olfativas-similares-a-carlisle-parfums-de-marly\/","url":"https:\/\/www.perfumeparlour.es\/product\/pennine-for-men-1008-pertenece-a-la-familia-de-notas-olfativas-similares-a-carlisle-parfums-de-marly\/","name":"PENNINE FOR MEN - 1008 - Pertenece a la familia de notas olfativas similares a Carlisle - Parfums de Marly\u00ae - Perfumes Parlour","isPartOf":{"@id":"https:\/\/www.perfumeparlour.es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.perfumeparlour.es\/product\/pennine-for-men-1008-pertenece-a-la-familia-de-notas-olfativas-similares-a-carlisle-parfums-de-marly\/#primaryimage"},"image":{"@id":"https:\/\/www.perfumeparlour.es\/product\/pennine-for-men-1008-pertenece-a-la-familia-de-notas-olfativas-similares-a-carlisle-parfums-de-marly\/#primaryimage"},"thumbnailUrl":"https:\/\/www.perfumeparlour.es\/wp-content\/uploads\/2025\/03\/Pennine-For-Men_45755bd3-4f46-4617-80ad-691fb281dbbd.webp","datePublished":"2025-03-09T18:40:19+00:00","dateModified":"2026-05-10T15:20:14+00:00","breadcrumb":{"@id":"https:\/\/www.perfumeparlour.es\/product\/pennine-for-men-1008-pertenece-a-la-familia-de-notas-olfativas-similares-a-carlisle-parfums-de-marly\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.perfumeparlour.es\/product\/pennine-for-men-1008-pertenece-a-la-familia-de-notas-olfativas-similares-a-carlisle-parfums-de-marly\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.perfumeparlour.es\/product\/pennine-for-men-1008-pertenece-a-la-familia-de-notas-olfativas-similares-a-carlisle-parfums-de-marly\/#primaryimage","url":"https:\/\/www.perfumeparlour.es\/wp-content\/uploads\/2025\/03\/Pennine-For-Men_45755bd3-4f46-4617-80ad-691fb281dbbd.webp","contentUrl":"https:\/\/www.perfumeparlour.es\/wp-content\/uploads\/2025\/03\/Pennine-For-Men_45755bd3-4f46-4617-80ad-691fb281dbbd.webp","width":800,"height":1200},{"@type":"BreadcrumbList","@id":"https:\/\/www.perfumeparlour.es\/product\/pennine-for-men-1008-pertenece-a-la-familia-de-notas-olfativas-similares-a-carlisle-parfums-de-marly\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.perfumeparlour.es\/"},{"@type":"ListItem","position":2,"name":"Tienda","item":"https:\/\/www.perfumeparlour.es\/shop\/"},{"@type":"ListItem","position":3,"name":"PENNINE FOR MEN &#8211; 1008 &#8211; Pertenece a la familia de notas olfativas similares a Carlisle &#8211; Parfums de Marly\u00ae"}]},{"@type":"WebSite","@id":"https:\/\/www.perfumeparlour.es\/#website","url":"https:\/\/www.perfumeparlour.es\/","name":"Perfumes Parlour","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.perfumeparlour.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.perfumeparlour.es\/en\/wp-json\/wp\/v2\/product\/6295","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.perfumeparlour.es\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.perfumeparlour.es\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.perfumeparlour.es\/en\/wp-json\/wp\/v2\/comments?post=6295"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.perfumeparlour.es\/en\/wp-json\/wp\/v2\/media\/7726"}],"wp:attachment":[{"href":"https:\/\/www.perfumeparlour.es\/en\/wp-json\/wp\/v2\/media?parent=6295"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.perfumeparlour.es\/en\/wp-json\/wp\/v2\/product_brand?post=6295"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.perfumeparlour.es\/en\/wp-json\/wp\/v2\/product_cat?post=6295"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.perfumeparlour.es\/en\/wp-json\/wp\/v2\/product_tag?post=6295"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}